{"id":109751,"date":"2024-04-12T14:05:15","date_gmt":"2024-04-12T12:05:15","guid":{"rendered":"https:\/\/popermint.com\/?post_type=product&#038;p=109751"},"modified":"2026-06-25T11:09:39","modified_gmt":"2026-06-25T09:09:39","slug":"shupatto-torba-arare-hailstone-m","status":"publish","type":"product","link":"https:\/\/popermint.com\/sl\/shupatto-torba-arare-hailstone-m\/","title":{"rendered":"Arare Hailstone M"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Shupatto trendovske lahke torbe se z enim samim potegom hitro zlo\u017eijo v kompaktno obliko. Inovativna zasnova ji omogo\u010da, da je v zlo\u017eenem polo\u017eaju izredno majhnih dimenzij, zato jo imate lahko vedno pri sebi. Razli\u010dne velikosti, barve in potiski zadostijo vsem potrebam. Izdelane so trajnostno, z minimalnim odpadnim materialom in so pralne v pralnem stroju.<\/p>\n","protected":false},"featured_media":109588,"template":"","meta":[],"product_brand":[],"product_cat":[836,838],"product_tag":[],"class_list":{"0":"post-109751","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-torbe-shupatto","7":"product_cat-torbe-m-shupatto","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/popermint.com\/sl\/wp-json\/wp\/v2\/product\/109751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popermint.com\/sl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popermint.com\/sl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popermint.com\/sl\/wp-json\/wp\/v2\/media\/109588"}],"wp:attachment":[{"href":"https:\/\/popermint.com\/sl\/wp-json\/wp\/v2\/media?parent=109751"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popermint.com\/sl\/wp-json\/wp\/v2\/product_brand?post=109751"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popermint.com\/sl\/wp-json\/wp\/v2\/product_cat?post=109751"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popermint.com\/sl\/wp-json\/wp\/v2\/product_tag?post=109751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}